{"id":1702,"date":"2026-04-14T15:08:37","date_gmt":"2026-04-14T13:08:37","guid":{"rendered":"https:\/\/swisswhoswho.ch\/?p=1702"},"modified":"2026-04-14T15:14:18","modified_gmt":"2026-04-14T13:14:18","slug":"lob-der-kultur","status":"publish","type":"post","link":"https:\/\/swisswhoswho.ch\/de\/alle-editorials\/gesellschaft-und-einfluss\/lob-der-kultur\/","title":{"rendered":"Lob der Kultur"},"content":{"rendered":"<p>Die Schweiz gl\u00e4nzt nicht nur durch ihre Wirtschaft oder ihre Stabilit\u00e4t: Ihre wahre St\u00e4rke ist ihre Kultur. Weit \u00fcber die Museen hinaus gestaltet sie den Alltag, verbindet die B\u00fcrger und verleiht dem Zusammenleben einen Sinn. Zwischen gro\u00dfen Institutionen und lokalen Initiativen baut die Kultur Br\u00fccken zwischen Sprachen und Regionen. Sie ist es, die es einer Gesellschaft erm\u00f6glicht, sich zu verstehen, voneinander zu erz\u00e4hlen und gemeinsam voranzukommen.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Die Schweiz gl\u00e4nzt nicht nur durch ihre Wirtschaft oder ihre Stabilit\u00e4t: Ihre wahre St\u00e4rke ist ihre Kultur. Weit \u00fcber die Museen hinaus gestaltet sie den Alltag, verbindet die B\u00fcrger und verleiht dem Zusammenleben einen Sinn. Zwischen gro\u00dfen Institutionen und lokalen Initiativen baut die Kultur Br\u00fccken zwischen Sprachen und Regionen. Das ist es, was [...].<\/p>","protected":false},"author":1,"featured_media":1703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"pmpro_default_level":"","footnotes":""},"categories":[40,27],"tags":[],"class_list":["post-1702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-plus-apprecies","category-societe-et-influence","pmpro-has-access"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9loge de la culture Suisse | Soci\u00e9t\u00e9 &amp; influence | Swiss Who\u2019s Who<\/title>\n<meta name=\"description\" content=\"La culture suisse, bien plus qu\u2019un patrimoine : un pilier du vivre-ensemble, du dialogue entre r\u00e9gions et de l\u2019identit\u00e9 collective dans un pays multiculturel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/swisswhoswho.ch\/de\/alle-editorials\/gesellschaft-und-einfluss\/lob-der-kultur\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9loge de la culture Suisse | Soci\u00e9t\u00e9 &amp; influence | Swiss Who\u2019s Who\" \/>\n<meta property=\"og:description\" content=\"La culture suisse, bien plus qu\u2019un patrimoine : un pilier du vivre-ensemble, du dialogue entre r\u00e9gions et de l\u2019identit\u00e9 collective dans un pays multiculturel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swisswhoswho.ch\/de\/alle-editorials\/gesellschaft-und-einfluss\/lob-der-kultur\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Who&#039;s Who\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T13:08:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T13:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"931\" \/>\n\t<meta property=\"og:image:height\" content=\"453\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"H\u00e9din J\u00e9r\u00e9my\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9din J\u00e9r\u00e9my\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/\"},\"author\":{\"name\":\"H\u00e9din J\u00e9r\u00e9my\",\"@id\":\"https:\/\/swisswhoswho.ch\/#\/schema\/person\/a46bd25d558bfb1afce78e6d76be26e2\"},\"headline\":\"\u00c9loge de la culture\",\"datePublished\":\"2026-04-14T13:08:37+00:00\",\"dateModified\":\"2026-04-14T13:14:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/\"},\"wordCount\":77,\"publisher\":{\"@id\":\"https:\/\/swisswhoswho.ch\/#organization\"},\"image\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp\",\"articleSection\":[\"Les plus appr\u00e9ci\u00e9s\",\"Soci\u00e9t\u00e9 et Influence\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/\",\"url\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/\",\"name\":\"\u00c9loge de la culture Suisse | Soci\u00e9t\u00e9 & influence | Swiss Who\u2019s Who\",\"isPartOf\":{\"@id\":\"https:\/\/swisswhoswho.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp\",\"datePublished\":\"2026-04-14T13:08:37+00:00\",\"dateModified\":\"2026-04-14T13:14:18+00:00\",\"description\":\"La culture suisse, bien plus qu\u2019un patrimoine : un pilier du vivre-ensemble, du dialogue entre r\u00e9gions et de l\u2019identit\u00e9 collective dans un pays multiculturel.\",\"breadcrumb\":{\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage\",\"url\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp\",\"contentUrl\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp\",\"width\":931,\"height\":453},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swisswhoswho.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9loge de la culture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swisswhoswho.ch\/#website\",\"url\":\"https:\/\/swisswhoswho.ch\/\",\"name\":\"Swiss Who's Who\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/swisswhoswho.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swisswhoswho.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/swisswhoswho.ch\/#organization\",\"name\":\"Swiss Who's Who\",\"url\":\"https:\/\/swisswhoswho.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/swisswhoswho.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2025\/11\/Logo-SWW.png\",\"contentUrl\":\"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2025\/11\/Logo-SWW.png\",\"width\":107,\"height\":62,\"caption\":\"Swiss Who's Who\"},\"image\":{\"@id\":\"https:\/\/swisswhoswho.ch\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/swisswhoswho.ch\/#\/schema\/person\/a46bd25d558bfb1afce78e6d76be26e2\",\"name\":\"H\u00e9din J\u00e9r\u00e9my\",\"sameAs\":[\"https:\/\/swisswhoswho.ch\"],\"url\":\"https:\/\/swisswhoswho.ch\/de\/author\/devsoo-oo-ch\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lob der Kultur Schweiz | Gesellschaft &amp; Einfluss | Swiss Who's Who","description":"Die Schweizer Kultur, mehr als nur ein Kulturerbe: ein Pfeiler des Zusammenlebens, des Dialogs zwischen den Regionen und der kollektiven Identit\u00e4t in einem multikulturellen Land.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/swisswhoswho.ch\/de\/alle-editorials\/gesellschaft-und-einfluss\/lob-der-kultur\/","og_locale":"de_DE","og_type":"article","og_title":"\u00c9loge de la culture Suisse | Soci\u00e9t\u00e9 & influence | Swiss Who\u2019s Who","og_description":"La culture suisse, bien plus qu\u2019un patrimoine : un pilier du vivre-ensemble, du dialogue entre r\u00e9gions et de l\u2019identit\u00e9 collective dans un pays multiculturel.","og_url":"https:\/\/swisswhoswho.ch\/de\/alle-editorials\/gesellschaft-und-einfluss\/lob-der-kultur\/","og_site_name":"Swiss Who&#039;s Who","article_published_time":"2026-04-14T13:08:37+00:00","article_modified_time":"2026-04-14T13:14:18+00:00","og_image":[{"width":931,"height":453,"url":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp","type":"image\/webp"}],"author":"H\u00e9din J\u00e9r\u00e9my","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"H\u00e9din J\u00e9r\u00e9my","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#article","isPartOf":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/"},"author":{"name":"H\u00e9din J\u00e9r\u00e9my","@id":"https:\/\/swisswhoswho.ch\/#\/schema\/person\/a46bd25d558bfb1afce78e6d76be26e2"},"headline":"\u00c9loge de la culture","datePublished":"2026-04-14T13:08:37+00:00","dateModified":"2026-04-14T13:14:18+00:00","mainEntityOfPage":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/"},"wordCount":77,"publisher":{"@id":"https:\/\/swisswhoswho.ch\/#organization"},"image":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage"},"thumbnailUrl":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp","articleSection":["Les plus appr\u00e9ci\u00e9s","Soci\u00e9t\u00e9 et Influence"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/","url":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/","name":"Lob der Kultur Schweiz | Gesellschaft &amp; Einfluss | Swiss Who's Who","isPartOf":{"@id":"https:\/\/swisswhoswho.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage"},"image":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage"},"thumbnailUrl":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp","datePublished":"2026-04-14T13:08:37+00:00","dateModified":"2026-04-14T13:14:18+00:00","description":"Die Schweizer Kultur, mehr als nur ein Kulturerbe: ein Pfeiler des Zusammenlebens, des Dialogs zwischen den Regionen und der kollektiven Identit\u00e4t in einem multikulturellen Land.","breadcrumb":{"@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#primaryimage","url":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp","contentUrl":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2026\/04\/Eloge-de-la-culture-sww.webp","width":931,"height":453},{"@type":"BreadcrumbList","@id":"https:\/\/swisswhoswho.ch\/tous-les-editorials\/societe-et-influence\/eloge-de-la-culture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swisswhoswho.ch\/"},{"@type":"ListItem","position":2,"name":"\u00c9loge de la culture"}]},{"@type":"WebSite","@id":"https:\/\/swisswhoswho.ch\/#website","url":"https:\/\/swisswhoswho.ch\/","name":"Swiss Who's Who","description":"","publisher":{"@id":"https:\/\/swisswhoswho.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swisswhoswho.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/swisswhoswho.ch\/#organization","name":"Swiss Who's Who","url":"https:\/\/swisswhoswho.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/swisswhoswho.ch\/#\/schema\/logo\/image\/","url":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2025\/11\/Logo-SWW.png","contentUrl":"https:\/\/swisswhoswho.ch\/wp-content\/uploads\/2025\/11\/Logo-SWW.png","width":107,"height":62,"caption":"Swiss Who's Who"},"image":{"@id":"https:\/\/swisswhoswho.ch\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/swisswhoswho.ch\/#\/schema\/person\/a46bd25d558bfb1afce78e6d76be26e2","name":"H\u00e9din J\u00e9r\u00e9my","sameAs":["https:\/\/swisswhoswho.ch"],"url":"https:\/\/swisswhoswho.ch\/de\/author\/devsoo-oo-ch\/"}]}},"_links":{"self":[{"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/posts\/1702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/comments?post=1702"}],"version-history":[{"count":7,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/posts\/1702\/revisions"}],"predecessor-version":[{"id":1711,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/posts\/1702\/revisions\/1711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/media\/1703"}],"wp:attachment":[{"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/media?parent=1702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/categories?post=1702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swisswhoswho.ch\/de\/wp-json\/wp\/v2\/tags?post=1702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}